{"id":11,"count":4,"description":"","link":"https:\/\/beepower.hr\/en\/category\/slatke-vijesti\/","name":"Sweet News","slug":"slatke-vijesti","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Slatke vijesti Archives - P\u010delinji proizvodi - Bee Power<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beepower.hr\/en\/category\/slatke-vijesti\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slatke vijesti Archives - P\u010delinji proizvodi - Bee Power\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beepower.hr\/en\/category\/slatke-vijesti\/\" \/>\n<meta property=\"og:site_name\" content=\"P\u010delinji proizvodi - Bee Power\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/beepower.hr\\\/category\\\/slatke-vijesti\\\/\",\"url\":\"https:\\\/\\\/beepower.hr\\\/category\\\/slatke-vijesti\\\/\",\"name\":\"Slatke vijesti Archives - P\u010delinji proizvodi - Bee Power\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beepower.hr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beepower.hr\\\/category\\\/slatke-vijesti\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beepower.hr\\\/category\\\/slatke-vijesti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Naslovna\",\"item\":\"https:\\\/\\\/beepower.hr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slatke vijesti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beepower.hr\\\/#website\",\"url\":\"https:\\\/\\\/beepower.hr\\\/\",\"name\":\"P\u010delinji proizvodi - Bee Power\",\"description\":\"Bee Power - snaga p\u010dela, najsla\u0111e blago prirode\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beepower.hr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Slatke vijesti Archives - P\u010delinji proizvodi - Bee Power","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beepower.hr\/en\/category\/slatke-vijesti\/","og_locale":"en_US","og_type":"article","og_title":"Slatke vijesti Archives - P\u010delinji proizvodi - Bee Power","og_url":"https:\/\/beepower.hr\/en\/category\/slatke-vijesti\/","og_site_name":"P\u010delinji proizvodi - Bee Power","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/beepower.hr\/category\/slatke-vijesti\/","url":"https:\/\/beepower.hr\/category\/slatke-vijesti\/","name":"Slatke vijesti Archives - P\u010delinji proizvodi - Bee Power","isPartOf":{"@id":"https:\/\/beepower.hr\/#website"},"breadcrumb":{"@id":"https:\/\/beepower.hr\/category\/slatke-vijesti\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/beepower.hr\/category\/slatke-vijesti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Naslovna","item":"https:\/\/beepower.hr\/"},{"@type":"ListItem","position":2,"name":"Slatke vijesti"}]},{"@type":"WebSite","@id":"https:\/\/beepower.hr\/#website","url":"https:\/\/beepower.hr\/","name":"P\u010delinji proizvodi - Bee Power","description":"Bee Power - snaga p\u010dela, najsla\u0111e blago prirode","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beepower.hr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/beepower.hr\/en\/wp-json\/wp\/v2\/categories\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beepower.hr\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/beepower.hr\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/beepower.hr\/en\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}